{"id":1501,"date":"2025-03-05T19:15:39","date_gmt":"2025-03-06T02:15:39","guid":{"rendered":"https:\/\/similasan.ca\/ingredients\/"},"modified":"2025-04-02T15:52:21","modified_gmt":"2025-04-02T21:52:21","slug":"ingredients","status":"publish","type":"page","link":"https:\/\/similasan.ca\/fr\/ingredients\/","title":{"rendered":"Ingr\u00e9dients"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1442px;margin-left: calc(-3% \/ 2 );margin-right: calc(-3% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.455%;--awb-margin-bottom-large:35px;--awb-spacing-left-large:1.455%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.455%;--awb-spacing-left-medium:1.455%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.455%;--awb-margin-bottom-small:10px;--awb-spacing-left-small:1.455%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:50;line-height:var(--awb-typography1-line-height);\">Ingr\u00e9dients<\/h1><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1442px;margin-left: calc(-3% \/ 2 );margin-right: calc(-3% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-right:35px;--awb-padding-left:35px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.455%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.455%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.455%;--awb-spacing-left-medium:1.455%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.455%;--awb-spacing-left-small:1.455%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"ingredient-nav\"><div class=\"ingredient-nav-label\">Show: <\/div><div class=\"button\" data-filter=\".a-e-fr\">A-E<\/div><div class=\"button\" data-filter=\".f-j-fr\">F-J<\/div><div class=\"button\" data-filter=\".k-o-fr\">K-O<\/div><div class=\"button\" data-filter=\".p-t-fr\">P-T<\/div><div class=\"button\" data-filter=\"all\">TOUT<\/div><\/div><!--category-nav--><div class=\"ingredientscontainer\"><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-apis.jpg\" class=\"ing-image wp-post-image\" alt=\"Apis mellifica\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-apis-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-apis.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Apis mellifica<\/h3><p>Apis est destin\u00e9 \u00e0 soulager temporairement les sympt\u00f4mes mineurs, comme les sensations de br\u00fblures, de d\u00e9mangeaison et de picotement. On le retrouve dans les gouttes st\u00e9riles Soulagement des yeux irrit\u00e9s par l\u2019allergie de Similasan. (\u00e0 base d\u2019insectes)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-arnica.jpg\" class=\"ing-image wp-post-image\" alt=\"Arnica montana\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-arnica-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-arnica.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Arnica montana<\/h3><p>Une plante europ\u00e9enne \u00e0 fleurs jaunes utilis\u00e9e comme rem\u00e8de m\u00e9dicinal pour traiter le bourdonnement dans les oreilles. On la retrouve dans le rem\u00e8de pour le bourdonnement des oreilles. (\u00e0 base de plante)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-belladonna.jpg\" class=\"ing-image wp-post-image\" alt=\"Belladone\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-belladonna-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-belladonna.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Belladone<\/h3><p>Destin\u00e9e au soulagement temporaire de la rougeur, de la sensation de br\u00fblure et de la sensation de grains de sable dans les yeux. On la retrouve dans les gouttes oculaires Soulagement des yeux secs, Soulagement de la conjonctivite et Soulagement complet des yeux de Similasan. (\u00e0 base de plante)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" src=\"\/wp-content\/themes\/Avada-Child-Theme\/images\/glossary-default.png\" alt=\"Causticum\" class=\"ing-image wp-post-image\"><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Causticum<\/h3><p>Destin\u00e9 au soulagement temporaire des sympt\u00f4mes de l\u2019accumulation du c\u00e9rumen, de l\u2019\u00e9coulement des oreilles et des d\u00e9mangeaisons. On le retrouve dans les gouttes auriculaires Traitement des bouchons de c\u00e9rum de Similasan. (\u00e0 base de min\u00e9raux)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-chamomilla.jpg\" class=\"ing-image wp-post-image\" alt=\"Chamomilla\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-chamomilla-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-chamomilla.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Chamomilla<\/h3><p>Destin\u00e9e au soulagement temporaire de la sensibilit\u00e9 aux courants d\u2019air et des malaises des oreilles dans les gouttes auriculaires Soulagement du mal d\u2019oreille de Similasan.<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-cinchona.jpg\" class=\"ing-image wp-post-image\" alt=\"Cinchona\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-cinchona-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-cinchona.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Cinchona<\/h3><p>Cet ingr\u00e9dient est destin\u00e9 au soulagement temporaire des sympt\u00f4mes de bourdonnements et de ronronnements dans les oreilles. Il se retrouve dans le rem\u00e8de pour le bourdonnement des oreilles. (\u00e0 base de plantes)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Conium-maculatum.jpg\" class=\"ing-image wp-post-image\" alt=\"Conium maculatum\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Conium-maculatum-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Conium-maculatum.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Conium maculatum<\/h3><p>Aussi connu sous le nom de pruche, il est destin\u00e9 au soulagement temporaire de la vision double, le larmoiement excessif, la douleur, une apparence rouge des objets, la sensibilit\u00e9 \u00e0 la lumi\u00e8re, des \u0153d\u00e8mes douloureux et la rougeur des orgelets. On le retrouve dans les gouttes oculaires st\u00e9riles Soulagement des orgelets. (\u00e0 base de plantes)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Eriodictyon_californicum.jpg\" class=\"ing-image wp-post-image\" alt=\"Eriodictyon californicum\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Eriodictyon_californicum-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Eriodictyon_californicum.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Eriodictyon californicum<\/h3><p>Cet ingr\u00e9dient est destin\u00e9 au soulagement temporaire des sympt\u00f4mes de malaise aux oreilles et d\u2019\u00e9tourdissement. On le retrouve dans le rem\u00e8de pour le bourdonnement des oreilles. (\u00e0 base de plante)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix a-e-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-euphrasia.jpg\" class=\"ing-image wp-post-image\" alt=\"Euphrasie\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-euphrasia-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-euphrasia.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Euphrasie<\/h3><p>Destin\u00e9e au soulagement temporaire des sympt\u00f4mes mineurs comme un mucus \u00e9pais ou le larmoiement, la sensation de br\u00fblure et l\u2019enflure de la paupi\u00e8re. On la retrouve les gouttes oculaires st\u00e9riles Soulagement des yeux secs, Soulagement complet des yeux, Soulagement des yeux irrit\u00e9s par l\u2019allergie et Soulagement de la conjonctivite de Similasan. (\u00e0 base de plantes)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix f-j-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Graphites.jpg\" class=\"ing-image wp-post-image\" alt=\"Graphites\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Graphites-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Graphites.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Graphites<\/h3><p>Destin\u00e9s au soulagement temporaire de la s\u00e9cheresse de l\u2019oreille interne, l\u2019accumulation de c\u00e9rumen, la sensation de bouchon et du bourdonnement. Ils sont aussi destin\u00e9s au soulagement temporaire de la rougeur des yeux et du larmoiement. On les retrouve dans les gouttes auriculaires Traitement des bouchons de c\u00e9rum et les gouttes oculaires st\u00e9riles Soulagement des orgelets de Similasan. (\u00e0 base de min\u00e9raux)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix f-j-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-hepar.jpg\" class=\"ing-image wp-post-image\" alt=\"Hepar sulphuris\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-hepar-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-hepar.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Hepar sulphuris<\/h3><p>Hepar sulphuris est destin\u00e9 au soulagement temporaire de la s\u00e9cheresse, le picotement, les sensations de br\u00fblure et du larmoiement des yeux et des paupi\u00e8res en raison des stress environnementaux. On le retrouve dans les rem\u00e8des Soulagement de la conjonctivite et Ear Ringing Relief. (\u00e0 base de min\u00e9raux, sous-produits animaux)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix k-o-fr\"><div class=\"ing-pic\"><img decoding=\"async\" src=\"\/wp-content\/themes\/Avada-Child-Theme\/images\/glossary-default.png\" alt=\"Lachesis\" class=\"ing-image wp-post-image\"><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Lachesis<\/h3><p>Destin\u00e9 au soulagement temporaire de l\u2019accumulation du c\u00e9rumen et de la s\u00e9cheresse des oreilles lorsqu\u2019il est utilis\u00e9 dans les gouttes auriculaires Traitement des bouchons de c\u00e9rum de Similasan. Soulagement temporaire des sympt\u00f4mes des pulsations, du tintement, le grondement, le craquement, le bourdonnement, le roulement, le sifflement et le bruit dans les oreilles lorsqu\u2019il est utilis\u00e9 dans le rem\u00e8de pour le bourdonnement dans les oreilles. (\u00e0 base animale)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix k-o-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Lycopodium.jpg\" class=\"ing-image wp-post-image\" alt=\"Lycopodium\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Lycopodium-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Lycopodium.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Lycopodium<\/h3><p>Aussi connu sous le nom de lycopode. Conseill\u00e9 pour le soulagement temporaire des sympt\u00f4mes de la sensation de bouchon dans les oreilles, ainsi que le bourdonnement dans l\u2019oreille. On le retrouve dans les gouttes auriculaires Traitement des bouchons de c\u00e9rum et les gouttes auriculaires Rem\u00e8de pour le bourdement des oreilles de Similasan. (\u00e0 base de plantes)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix k-o-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-mercurius.jpg\" class=\"ing-image wp-post-image\" alt=\"Mercurius sublimatus\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-mercurius-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-mercurius.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Mercurius sublimatus<\/h3><p>Aussi connu comme Mercurius corrosivus ou Mercuric Chloride, il est destin\u00e9 au soulagement temporaire des yeux et des paupi\u00e8res rouges, ainsi que les sensations de br\u00fblure et de s\u00e9cheresse des yeux. Cette forme de mercurius est non toxique. On le retrouve dans les gouttes oculaires st\u00e9riles Soulagement des yeux secs et Soulagement complet des yeux de Similasan. (\u00e0 base de m\u00e9tal)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix p-t-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-sabadilla.jpg\" class=\"ing-image wp-post-image\" alt=\"Sabadilla\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-sabadilla-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-sabadilla.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Sabadilla<\/h3><p>Conseill\u00e9 pour le larmoiement, les sensations de br\u00fblure et la d\u00e9mangeaison des yeux. On le retrouve dans les gouttes oculaires Soulagement des yeux irrit\u00e9s par l\u2019allergie de Similasan. (\u00e0 base de plantes)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix p-t-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-silicea.jpg\" class=\"ing-image wp-post-image\" alt=\"Silice\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-silicea-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-silicea.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Silice<\/h3><p>Cet ingr\u00e9dient est destin\u00e9 au soulagement temporaire des sympt\u00f4mes de tintement, de gloussement, de ronronnement, de chant et de bruits dans les oreilles. On le retrouve dans le rem\u00e8de pour le bourdonnement des oreilles. (\u00e0 base de min\u00e9raux)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix p-t-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-sulphur.jpg\" class=\"ing-image wp-post-image\" alt=\"Soufre\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-sulphur-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-sulphur.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Soufre<\/h3><p>Aussi connu comme soufre \u00e9l\u00e9mentaire, il est destin\u00e9 au soulagement temporaire de la douleur, des d\u00e9mangeaisons et du bourdonnement dans les oreilles, ainsi que l\u2019enflure, le larmoiement et la rougeur des yeux. Le soufre \u00e9l\u00e9mentaire, qui se retrouve dans la nature, repr\u00e9sente 0,25 % du poids du corps humain et n\u2019est pas consid\u00e9r\u00e9 comme allerg\u00e8ne. On ne devrait pas confondre cet ingr\u00e9dient avec les allerg\u00e8nes courants comme les sulfamides et les sulfites que l\u2019on retrouve dans plusieurs m\u00e9dicaments d\u2019ordonnance et d\u2019autres produits. On le retrouve dans les gouttes oculaires st\u00e9riles Soulagement des orgelets et les gouttes auriculaires Earache Relief de Similasan. (\u00e0 base de min\u00e9raux)<\/p>\n<\/div><\/div><div id=\"ingredient\" class=\"mix p-t-fr\"><div class=\"ing-pic\"><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Thiosinaminum.jpg\" class=\"ing-image wp-post-image\" alt=\"Thiosinaminum\" srcset=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Thiosinaminum-66x66.jpg 66w, https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/ing-Thiosinaminum.jpg 120w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div><div class=\"ing-detail\"><h3 class=\"ing-title\">Thiosinaminum<\/h3><p>Cet ingr\u00e9dient est destin\u00e9 au soulagement temporaire des sympt\u00f4mes de bourdonnement et de p\u00e9piement dans les oreilles. On le retrouve dans le rem\u00e8de pour le bourdonnement des oreilles. (\u00e0 base de plante)<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1501","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ingr\u00e9dients | Similasan Canada<\/title>\n<meta name=\"description\" content=\"Similasan s&#039;engage \u00e0 aider les familles \u00e0 se sentir mieux. Nos rem\u00e8des naturels soulagent temporairement les sympt\u00f4mes des affections oculaires, auriculaires, nasales, c\u00e9r\u00e9brales et thoraciques sans utiliser de produits chimiques agressifs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/similasan.ca\/fr\/ingredients\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingr\u00e9dients | Similasan Canada\" \/>\n<meta property=\"og:description\" content=\"Similasan s&#039;engage \u00e0 aider les familles \u00e0 se sentir mieux. Nos rem\u00e8des naturels soulagent temporairement les sympt\u00f4mes des affections oculaires, auriculaires, nasales, c\u00e9r\u00e9brales et thoraciques sans utiliser de produits chimiques agressifs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/similasan.ca\/fr\/ingredients\/\" \/>\n<meta property=\"og:site_name\" content=\"Similasan Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Similasan\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T21:52:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/Similasan1200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/ingredients\\\/\",\"url\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/ingredients\\\/\",\"name\":\"Ingr\u00e9dients | Similasan Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/#website\"},\"datePublished\":\"2025-03-06T02:15:39+00:00\",\"dateModified\":\"2025-04-02T21:52:21+00:00\",\"description\":\"Similasan s'engage \u00e0 aider les familles \u00e0 se sentir mieux. Nos rem\u00e8des naturels soulagent temporairement les sympt\u00f4mes des affections oculaires, auriculaires, nasales, c\u00e9r\u00e9brales et thoraciques sans utiliser de produits chimiques agressifs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/ingredients\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/similasan.ca\\\/fr\\\/ingredients\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/ingredients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ingr\u00e9dients\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/\",\"name\":\"Similasan Canada\",\"description\":\"Feel Good About Feeling Better\u2122\",\"publisher\":{\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/#organization\",\"name\":\"Similasan\",\"url\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/similasan.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Similasan696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/similasan.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Similasan696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Similasan\"},\"image\":{\"@id\":\"https:\\\/\\\/similasan.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Similasan\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingr\u00e9dients | Similasan Canada","description":"Similasan s'engage \u00e0 aider les familles \u00e0 se sentir mieux. Nos rem\u00e8des naturels soulagent temporairement les sympt\u00f4mes des affections oculaires, auriculaires, nasales, c\u00e9r\u00e9brales et thoraciques sans utiliser de produits chimiques agressifs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/similasan.ca\/fr\/ingredients\/","og_locale":"fr_CA","og_type":"article","og_title":"Ingr\u00e9dients | Similasan Canada","og_description":"Similasan s'engage \u00e0 aider les familles \u00e0 se sentir mieux. Nos rem\u00e8des naturels soulagent temporairement les sympt\u00f4mes des affections oculaires, auriculaires, nasales, c\u00e9r\u00e9brales et thoraciques sans utiliser de produits chimiques agressifs.","og_url":"https:\/\/similasan.ca\/fr\/ingredients\/","og_site_name":"Similasan Canada","article_publisher":"https:\/\/www.facebook.com\/Similasan","article_modified_time":"2025-04-02T21:52:21+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/Similasan1200.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/similasan.ca\/fr\/ingredients\/","url":"https:\/\/similasan.ca\/fr\/ingredients\/","name":"Ingr\u00e9dients | Similasan Canada","isPartOf":{"@id":"https:\/\/similasan.ca\/fr\/#website"},"datePublished":"2025-03-06T02:15:39+00:00","dateModified":"2025-04-02T21:52:21+00:00","description":"Similasan s'engage \u00e0 aider les familles \u00e0 se sentir mieux. Nos rem\u00e8des naturels soulagent temporairement les sympt\u00f4mes des affections oculaires, auriculaires, nasales, c\u00e9r\u00e9brales et thoraciques sans utiliser de produits chimiques agressifs.","breadcrumb":{"@id":"https:\/\/similasan.ca\/fr\/ingredients\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/similasan.ca\/fr\/ingredients\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/similasan.ca\/fr\/ingredients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/similasan.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Ingr\u00e9dients"}]},{"@type":"WebSite","@id":"https:\/\/similasan.ca\/fr\/#website","url":"https:\/\/similasan.ca\/fr\/","name":"Similasan Canada","description":"Feel Good About Feeling Better\u2122","publisher":{"@id":"https:\/\/similasan.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/similasan.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/similasan.ca\/fr\/#organization","name":"Similasan","url":"https:\/\/similasan.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/similasan.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/Similasan696-1.jpg","contentUrl":"https:\/\/similasan.ca\/wp-content\/uploads\/2025\/03\/Similasan696-1.jpg","width":696,"height":696,"caption":"Similasan"},"image":{"@id":"https:\/\/similasan.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Similasan"]}]}},"_links":{"self":[{"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/pages\/1501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/comments?post=1501"}],"version-history":[{"count":0,"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/pages\/1501\/revisions"}],"wp:attachment":[{"href":"https:\/\/similasan.ca\/fr\/wp-json\/wp\/v2\/media?parent=1501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}